{"id":638,"date":"2014-03-28T15:23:24","date_gmt":"2014-03-28T14:23:24","guid":{"rendered":"https:\/\/www.eporedia.com\/security-policy-procedures\/"},"modified":"2019-07-09T11:35:40","modified_gmt":"2019-07-09T10:35:40","slug":"las-politicas-y-los-procedimientos-de-seguridad","status":"publish","type":"page","link":"https:\/\/www.eporedia.com\/es\/las-politicas-y-los-procedimientos-de-seguridad\/","title":{"rendered":"Las Pol\u00edticas y los Procedimientos de Seguridad"},"content":{"rendered":"\n<div class=\"wp-block-uagb-section uagb-section__wrap uagb-section__background-image\" id=\"uagb-section-6a312b64-075b-4a0e-91f5-19324a0c7d75\"><div class=\"uagb-section__overlay\"><\/div><div class=\"uagb-section__inner-wrap\">\n<div class=\"wp-block-uagb-advanced-heading entry-header\" id=\"uagb-adv-heading-27d37e47-67e0-4676-b76f-cd56505adbe0\"><h1 class=\"uagb-heading-text\"><strong>LAS POLIT\u00cdCAS Y LOS PROCEDIMENTOS DE SEGURIDAD<\/strong><\/h1><p class=\"uagb-desc-text\"><\/p><\/div>\n\n\n\n<p><\/p>\n<\/div><\/div>\n\n\n\n<section class=\"wp-block-uagb-section uagb-section__wrap uagb-section__background-undefined\" id=\"uagb-section-0e04527e-3c08-4488-9873-d2f8fa3b9270\"><div class=\"uagb-section__overlay\"><\/div><div class=\"uagb-section__inner-wrap\">\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>Las Pol\u00edticas y los Procedimientos de Seguridad<\/strong><\/p>\n\n\n\n<p>Las Pol\u00edticas y los Procedimientos definen el punto de vista individual de cada empresa sobre su seguridad. Un buen conjunto de pol\u00edticas y procedimientos puede facilitar, en gran medida, el mantenimiento de un alto nivel de seguridad de la informaci\u00f3n.<\/p>\n\n\n\n<p>Los Consultores de Eporedia han entregado exitosamente pol\u00edticas y procedimientos para las empresas de transporte tanto ferroviario como a\u00e9reo del Reino Unido.<\/p>\n\n\n\n<p>Eporedia provee un enfoque pragm\u00e1tico de las pol\u00edticas y los procedimientos, asegurando el cumplimiento de las normas tales como: BS 7799 \/ ISO 27001 y PCI, sin restringir los procesos de negocio, permiti\u00e9ndole a la empresa continuar con su trabajo, aunque de una manera m\u00e1s segura.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"page-builder","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"enabled","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-638","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Las Pol\u00edticas y los Procedimientos de Seguridad - Eporedia<\/title>\n<meta name=\"description\" content=\"Las Pol\u00edticas y los Procedimientos definen el punto de vista individual de cada empresa sobre su seguridad. Un buen conjunto de pol\u00edticas y procedimientos puede facilitar, en gran medida, el mantenimiento de un alto nivel de seguridad de la informaci\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eporedia.com\/es\/las-politicas-y-los-procedimientos-de-seguridad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las Pol\u00edticas y los Procedimientos de Seguridad - Eporedia\" \/>\n<meta property=\"og:description\" content=\"Las Pol\u00edticas y los Procedimientos definen el punto de vista individual de cada empresa sobre su seguridad. Un buen conjunto de pol\u00edticas y procedimientos puede facilitar, en gran medida, el mantenimiento de un alto nivel de seguridad de la informaci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eporedia.com\/es\/las-politicas-y-los-procedimientos-de-seguridad\/\" \/>\n<meta property=\"og:site_name\" content=\"Eporedia\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-09T10:35:40+00:00\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.eporedia.com\/es\/las-politicas-y-los-procedimientos-de-seguridad\/\",\"url\":\"https:\/\/www.eporedia.com\/es\/las-politicas-y-los-procedimientos-de-seguridad\/\",\"name\":\"Las Pol\u00edticas y los Procedimientos de Seguridad - Eporedia\",\"isPartOf\":{\"@id\":\"https:\/\/www.eporedia.com\/es\/#website\"},\"datePublished\":\"2014-03-28T14:23:24+00:00\",\"dateModified\":\"2019-07-09T10:35:40+00:00\",\"description\":\"Las Pol\u00edticas y los Procedimientos definen el punto de vista individual de cada empresa sobre su seguridad. Un buen conjunto de pol\u00edticas y procedimientos puede facilitar, en gran medida, el mantenimiento de un alto nivel de seguridad de la informaci\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.eporedia.com\/es\/las-politicas-y-los-procedimientos-de-seguridad\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.eporedia.com\/es\/las-politicas-y-los-procedimientos-de-seguridad\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.eporedia.com\/es\/las-politicas-y-los-procedimientos-de-seguridad\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.eporedia.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las Pol\u00edticas y los Procedimientos de Seguridad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.eporedia.com\/es\/#website\",\"url\":\"https:\/\/www.eporedia.com\/es\/\",\"name\":\"Eporedia\",\"description\":\"Your IT Security Partners\",\"publisher\":{\"@id\":\"https:\/\/www.eporedia.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.eporedia.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.eporedia.com\/es\/#organization\",\"name\":\"Eporedia\",\"url\":\"https:\/\/www.eporedia.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.eporedia.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.eporedia.com\/wp-content\/uploads\/2019\/06\/cropped-Logo_eporedia1-e1396441304476-1.png\",\"contentUrl\":\"https:\/\/www.eporedia.com\/wp-content\/uploads\/2019\/06\/cropped-Logo_eporedia1-e1396441304476-1.png\",\"width\":260,\"height\":73,\"caption\":\"Eporedia\"},\"image\":{\"@id\":\"https:\/\/www.eporedia.com\/es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las Pol\u00edticas y los Procedimientos de Seguridad - Eporedia","description":"Las Pol\u00edticas y los Procedimientos definen el punto de vista individual de cada empresa sobre su seguridad. Un buen conjunto de pol\u00edticas y procedimientos puede facilitar, en gran medida, el mantenimiento de un alto nivel de seguridad de la informaci\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eporedia.com\/es\/las-politicas-y-los-procedimientos-de-seguridad\/","og_locale":"es_ES","og_type":"article","og_title":"Las Pol\u00edticas y los Procedimientos de Seguridad - Eporedia","og_description":"Las Pol\u00edticas y los Procedimientos definen el punto de vista individual de cada empresa sobre su seguridad. Un buen conjunto de pol\u00edticas y procedimientos puede facilitar, en gran medida, el mantenimiento de un alto nivel de seguridad de la informaci\u00f3n.","og_url":"https:\/\/www.eporedia.com\/es\/las-politicas-y-los-procedimientos-de-seguridad\/","og_site_name":"Eporedia","article_modified_time":"2019-07-09T10:35:40+00:00","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.eporedia.com\/es\/las-politicas-y-los-procedimientos-de-seguridad\/","url":"https:\/\/www.eporedia.com\/es\/las-politicas-y-los-procedimientos-de-seguridad\/","name":"Las Pol\u00edticas y los Procedimientos de Seguridad - Eporedia","isPartOf":{"@id":"https:\/\/www.eporedia.com\/es\/#website"},"datePublished":"2014-03-28T14:23:24+00:00","dateModified":"2019-07-09T10:35:40+00:00","description":"Las Pol\u00edticas y los Procedimientos definen el punto de vista individual de cada empresa sobre su seguridad. Un buen conjunto de pol\u00edticas y procedimientos puede facilitar, en gran medida, el mantenimiento de un alto nivel de seguridad de la informaci\u00f3n.","breadcrumb":{"@id":"https:\/\/www.eporedia.com\/es\/las-politicas-y-los-procedimientos-de-seguridad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eporedia.com\/es\/las-politicas-y-los-procedimientos-de-seguridad\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.eporedia.com\/es\/las-politicas-y-los-procedimientos-de-seguridad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.eporedia.com\/es\/"},{"@type":"ListItem","position":2,"name":"Las Pol\u00edticas y los Procedimientos de Seguridad"}]},{"@type":"WebSite","@id":"https:\/\/www.eporedia.com\/es\/#website","url":"https:\/\/www.eporedia.com\/es\/","name":"Eporedia","description":"Your IT Security Partners","publisher":{"@id":"https:\/\/www.eporedia.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eporedia.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.eporedia.com\/es\/#organization","name":"Eporedia","url":"https:\/\/www.eporedia.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eporedia.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.eporedia.com\/wp-content\/uploads\/2019\/06\/cropped-Logo_eporedia1-e1396441304476-1.png","contentUrl":"https:\/\/www.eporedia.com\/wp-content\/uploads\/2019\/06\/cropped-Logo_eporedia1-e1396441304476-1.png","width":260,"height":73,"caption":"Eporedia"},"image":{"@id":"https:\/\/www.eporedia.com\/es\/#\/schema\/logo\/image\/"}}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"admin_eporedia","author_link":"https:\/\/www.eporedia.com\/es\/author\/admin_eporedia\/"},"uagb_comment_info":0,"uagb_excerpt":null,"_links":{"self":[{"href":"https:\/\/www.eporedia.com\/es\/wp-json\/wp\/v2\/pages\/638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eporedia.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.eporedia.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.eporedia.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eporedia.com\/es\/wp-json\/wp\/v2\/comments?post=638"}],"version-history":[{"count":4,"href":"https:\/\/www.eporedia.com\/es\/wp-json\/wp\/v2\/pages\/638\/revisions"}],"predecessor-version":[{"id":937,"href":"https:\/\/www.eporedia.com\/es\/wp-json\/wp\/v2\/pages\/638\/revisions\/937"}],"wp:attachment":[{"href":"https:\/\/www.eporedia.com\/es\/wp-json\/wp\/v2\/media?parent=638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}